{"id":126,"date":"2026-03-28T10:46:12","date_gmt":"2026-03-28T10:46:12","guid":{"rendered":"https:\/\/nakara.org\/?p=126"},"modified":"2026-03-28T10:46:12","modified_gmt":"2026-03-28T10:46:12","slug":"menhir-de-drancy-93700-pierre-levee","status":"publish","type":"post","link":"https:\/\/nakara.org\/index.php\/2026\/03\/28\/menhir-de-drancy-93700-pierre-levee\/","title":{"rendered":"Menhir de Drancy 93700 Pierre-Lev\u00e9e"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">(les m\u00eames sources, du m\u00eame auteur) Sur le terroir de Drancy, c\u2019est vraisemblablement, par cette \u00ab route des seuils \u00bb que des groupes n\u00e9olithiques, venant du sud ou du nord, ont d\u00fb p\u00e9n\u00e9trer dans la Glauconia Sylva et peut-\u00eatre s\u2019y fixer, \u00e0 une certaine distance de la route, sur une aire de d\u00e9frichement. La piste d\u2019acc\u00e8s \u00e0 cette aire pourrait \u00eatre \u00e0 l\u2019origine de la rue de la R\u00e9publique, l\u2019ancien chemin de la Courneuve et de Saint-Denis qui, avant la coupure du chemin de fer, partait de la route de Flandre. Le n\u00e9olithique qui d\u00e9bute vers 4000 avant notre \u00e8re est caract\u00e9ris\u00e9 par les d\u00e9buts de l\u2019agriculture, de l\u2019\u00e9levage et de la s\u00e9dentarisation succ\u00e9dant \u00e0 une \u00e9conomie exclusive de chasse, de p\u00eache et de cueillette et se terminant par l\u2019apparition du m\u00e9tal (le cuivre). Des sites t\u00e9moins des installations n\u00e9olithiques et de leur d\u00e9veloppement se retrouvent dans le Bassin Parisien : ceux du Ruban\u00e9 r\u00e9cent, vers 3500, t\u00e9moins d\u2019une civilisation venue d\u2019Europe centrale par la vall\u00e9e du Rhin. Les sites du \u00ab groupe de Cerny \u00bb vers 3000 de type venu du nord de l\u2019Europe. Ceux du \u00ab Chass\u00e9en \u00bb vers 2500, d\u2019origine composite septentrionale, m\u00e9ridionale et orientale. Enfin, au-del\u00e0 de quelques autres types repr\u00e9sent\u00e9s localement et se situant autour des ann\u00e9es 2000, les sites nombreux dits de \u00ab Civilisation Seine Oise Marne \u00bb (S.O.M.) s\u2019\u00e9tendant de 2400 \u00e0 1700, d\u2019origine \u00e0 la fois septentrionale et m\u00e9ridionale avec des \u00e9l\u00e9ments orientaux et occidentaux. Il se peut que, par la \u00ab route des seuils \u00bb des civilisations n\u00e9olithiques ant\u00e9rieures \u00e0 la civilisation \u00ab Seine Oise Marne \u00bb, aient p\u00e9n\u00e9tr\u00e9 le terroir du futur Drancy : nous n\u2019en n\u2019avons aucun indice. Mais le fait qu\u2019il existe \u00e0 Drancy un lieu-dit appel\u00e9 \u00ab La Haute Borne \u00bb don\u2019t le nom pourrait venir d\u2019un m\u00e9galithe, d\u2019une \u00ab pierre lev\u00e9e \u00bb, d\u2019un menhir tendrait \u00e0 prouver qu\u2019il y a eu \u00e0 Drancy, de passage ou en permanence, une pr\u00e9sence n\u00e9olithique. Or l\u2019une des caract\u00e9ristiques marquant sp\u00e9cialement la civilisation \u00ab Seine Oise Marne \u00bb est justement celle des m\u00e9galithes : pierres lev\u00e9es et all\u00e9es couvertes (s\u00e9pultures collectives). Ce lieu-dit pourrait donc permettre de penser que la 1re occupation humaine connue sur le sol de Drancy se situerait entre 2400 et 1700, avec ses caract\u00e9ristiques. Comme autres caract\u00e9ristiques de la civilisation S.O.M. se trouvent les industries de la pierre, de l\u2019os et du bois de cerf et la fabrication d\u2019une c\u00e9ramique, se distinguant des m\u00eames industries des groupes n\u00e9olithiques ant\u00e9rieurs. Puis finalement une \u00e9bauche de l\u2019industrie du cuivre. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">93700 Menhir N\u00e9olithique Histoire local<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Menhir de Drancy 93700 Pierre Levee\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/gSaYOrPQEqk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>(les m\u00eames sources, du m\u00eame auteur) Sur le terroir de Drancy, c\u2019est vraisemblablement, par cette \u00ab route des seuils \u00bb que des groupes n\u00e9olithiques, venant du sud ou du nord, ont d\u00fb p\u00e9n\u00e9trer dans la Glauconia Sylva et peut-\u00eatre s\u2019y &hellip; <a href=\"https:\/\/nakara.org\/index.php\/2026\/03\/28\/menhir-de-drancy-93700-pierre-levee\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-126","post","type-post","status-publish","format-standard","hentry","category-doleances"],"_links":{"self":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts\/126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/comments?post=126"}],"version-history":[{"count":1,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts\/126\/revisions"}],"predecessor-version":[{"id":127,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts\/126\/revisions\/127"}],"wp:attachment":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/media?parent=126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/categories?post=126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/tags?post=126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}