{"id":139,"date":"2026-04-11T12:00:21","date_gmt":"2026-04-11T12:00:21","guid":{"rendered":"https:\/\/nakara.org\/?p=139"},"modified":"2026-04-11T12:03:21","modified_gmt":"2026-04-11T12:03:21","slug":"1789-la-courneuve-93120-cahier-de-doleances","status":"publish","type":"post","link":"https:\/\/nakara.org\/index.php\/2026\/04\/11\/1789-la-courneuve-93120-cahier-de-doleances\/","title":{"rendered":"1789 La Courneuve 93120 Cahier de Dol\u00e9ances"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"1789 La Courneuve 93120 Cahier de Dol\u00e9ances\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/RR11DrNw0tA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">LA COURNEUVE Cahier Des dol\u00e9ances de la paroisse de la Cour-Neuve. Les peuples des campagnes peuvent enfin faire entendre leur voix et porter leurs plaintes et dol\u00e9ances aux pieds du tr\u00f4ne. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Article 1. Classement des terres. Article 2. Abonnement de l\u2019imp\u00f4t par la province pour chaque municipalit\u00e9. Article 3. Imp\u00f4t pour les biens des campagnes, \u00e9tabli en totalit\u00e9 sur les propri\u00e9t\u00e9s. Article 4. Industrie du cultivateur lib\u00e9r\u00e9e de tout imp\u00f4t. Article 5. Suppression de tous les privil\u00e8ges. Article 6. Suppression du droit de franc-fief. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Article 7. Abolition du droit de lords et ventes. Article 8. Suppression totale des capitaineries. Article 9. Droit de chasse, born\u00e9 au propre sol du seigneur ou du particulier. Article 10. Rachat des d\u00eemes en un abonnement, en argent ou en grains.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Article 11. Rachat des sucres seigneuriaux et champarts. Article 12. Destruction ou tr\u00e8s-grande r\u00e9duction du droit de colombier. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Article 13. Libert\u00e9 \u00e0 tout propri\u00e9taire de faire sur son lot les am\u00e9liorations, changements, cl\u00f4tures, qu\u2019il jugera convenables. Article 14. Abonnement des d\u00eemes attribu\u00e9 aux cur\u00e9s de campagne et aux bureaux de charit\u00e9 \u00e9tablis dans toutes les paroisses. Article 15. Etablissement des tribunaux ruraux, o\u00f9 toutes les discussions des laboureurs seront port\u00e9es. Article 16. \u00c9tablissant d\u2019une caisse de bienfaisance pour les vieux domestiques et manouvriers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Article 17. Police sur les domestiques et ouvriers. Article 18. Taxation du pain dans les campagnes et sa meilleure fabrication. Article 19. Police sur l\u2019exportation des grains. Article 20. R\u00e9duction de toutes les mesures en une seule. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Article 21. \u00c9galit\u00e9 de poids dans tout le royaume. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1789 93120<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA COURNEUVE Cahier Des dol\u00e9ances de la paroisse de la Cour-Neuve. Les peuples des campagnes peuvent enfin faire entendre leur voix et porter leurs plaintes et dol\u00e9ances aux pieds du tr\u00f4ne. Article 1. Classement des terres. Article 2. Abonnement de &hellip; <a href=\"https:\/\/nakara.org\/index.php\/2026\/04\/11\/1789-la-courneuve-93120-cahier-de-doleances\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-139","post","type-post","status-publish","format-standard","hentry","category-doleances"],"_links":{"self":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts\/139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/comments?post=139"}],"version-history":[{"count":2,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts\/139\/revisions"}],"predecessor-version":[{"id":143,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts\/139\/revisions\/143"}],"wp:attachment":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/media?parent=139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/categories?post=139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/tags?post=139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}