{"id":164,"date":"2026-04-11T12:25:55","date_gmt":"2026-04-11T12:25:55","guid":{"rendered":"https:\/\/nakara.org\/?p=164"},"modified":"2026-04-11T12:25:55","modified_gmt":"2026-04-11T12:25:55","slug":"lac-parisien-en-ile-de-france","status":"publish","type":"post","link":"https:\/\/nakara.org\/index.php\/2026\/04\/11\/lac-parisien-en-ile-de-france\/","title":{"rendered":"Lac Parisien en \u00cele-de-France"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Lac Parisien en Ile-de-France\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/xxax5y4pAxk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">(du m\u00eame auteur et de la m\u00eame source)<br>Entre 25 000 et 7 000 \u00e0 l\u2019\u00e9poque glaciaire finissante, l\u2019abaissement des niveaux de la Seine et de la Marne, joint \u00e0 la diminution du volume d\u2019eau d\u00fb au recul des glaciers scandinaves et alpins, modifi\u00e8rent la topographie. Du \u00ab lac parisien \u00bb il ne resta plus qu\u2019un vaste plan d\u2019eau recouvrant Pavillons-sous-Bois en totalit\u00e9, Bondy et Bobigny en partie et Drancy presque enti\u00e8rement : cela \u00e0 la fin de la premi\u00e8re partie du quaternaire appel\u00e9e Pl\u00e9istoc\u00e8ne.<br>Quant aux \u00ab bras de la Marne \u00bb, celui de Sevran s\u2019\u00e9tait scind\u00e9 en deux cours d\u2019eau entourant le plateau limoneux et exond\u00e9 de Blanc-Mesnil et le bras de Villemomble longeait bien au sud le trac\u00e9 de la rue de Stalingrad actuelle. Tous trois se regroupaient \u00e0 l\u2019emplacement de Saint-Denis pour rejoindre la Seine \u00e0 la hauteur de la future Ile Saint-Denis. Le bras du Perreux rejoignait la Seine entre Charenton et Maisons-Alfort.<br>Finalement les trois bras venant du nord-est (les deux de Sevran et celui de Villemomble) disparurent compl\u00e8tement pour laisser leur lit, ceux de Sevran \u00e0 la Molette (ou Moleret) et \u00e0 la Mor\u00e9e, celui de Villemomble au r\u00fb du Montfort.<br>De plus au Plioc\u00e8ne (fin du tertiaire) il y avait eu un soul\u00e8vement g\u00e9n\u00e9ral du sol \u00e0 l\u2019emplacement de la Manche, de la Mer du Nord et du Bassin Parisien et le niveau des mers avait baiss\u00e9 par suite de l\u2019absorption de l\u2019eau par la glaciation. L\u2019Angleterre, la Hollande, le Danemark formaient un seul continent appel\u00e9 \u00ab Plateau Franco-Britannique \u00bb<br>Les cours d\u2019eau, la Seine, la Marne et l\u2019Oise, avaient consid\u00e9rablement augment\u00e9 leur volume et leur d\u00e9bit et tendaient \u00e0 modifier leur lit vers l\u2019aval soit en le creusant et l\u2019\u00e9largissant par la masse de leurs eaux, soit par leur divagation en m\u00e9andres. Les lits de la Seine, de la Marne et de l\u2019Oise \u00e9taient devenus tr\u00e8s larges et la hauteur des berges s\u2019\u00e9tait \u00e9lev\u00e9e jusqu\u2019\u00e0 60 m\u00e8tres. Ces cours d\u2019eau ont laiss\u00e9 des alluvions l\u00e0 o\u00f9 ils s\u2019\u00e9tendaient. \u00ab Tout accroissement des glaciers r\u00e9pond \u00e0 une recrudescence de l\u2019humidit\u00e9 du climat. Gonfl\u00e9s par des \u00e9t\u00e9s pluvieux qui liqu\u00e9fiaient la masse des neiges accumul\u00e9es pendant une longue saison froide.<br>Des volumes d\u2019eau que les conditions climatiques actuelles laissent difficilement imaginer \u00bb.<br>La Marne rejoignait la Seine en trois bras : au nord-est par S\u00e9vran et Villemomble, au sud-est par Le Perreux. Leur rencontre formait un immense lac, le \u00ab lac parisien \u00bb d\u2019o\u00f9 \u00e9mergeaient des \u00ab \u00eeles \u00bb, les hauteurs de Chaillot, de Montmartre et de Belleville.<br>Les berges de ce lac sont encore visibles. L\u2019emplacement de Drancy \u00e9tait donc compl\u00e8tement ennoy\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(du m\u00eame auteur et de la m\u00eame source)Entre 25 000 et 7 000 \u00e0 l\u2019\u00e9poque glaciaire finissante, l\u2019abaissement des niveaux de la Seine et de la Marne, joint \u00e0 la diminution du volume d\u2019eau d\u00fb au recul des glaciers scandinaves &hellip; <a href=\"https:\/\/nakara.org\/index.php\/2026\/04\/11\/lac-parisien-en-ile-de-france\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-164","post","type-post","status-publish","format-standard","hentry","category-doleances"],"_links":{"self":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts\/164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/comments?post=164"}],"version-history":[{"count":1,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts\/164\/revisions"}],"predecessor-version":[{"id":165,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts\/164\/revisions\/165"}],"wp:attachment":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/media?parent=164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/categories?post=164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/tags?post=164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}