{"id":44,"date":"2026-03-16T12:02:23","date_gmt":"2026-03-16T12:02:23","guid":{"rendered":"https:\/\/nakara.org\/?p=44"},"modified":"2026-03-16T12:23:36","modified_gmt":"2026-03-16T12:23:36","slug":"saint-deniscahier-des-plaintes-doleances-et-remontrances-de-lassemblee-du-tiers-etat-de-la-ville-de-saint-denis","status":"publish","type":"post","link":"https:\/\/nakara.org\/index.php\/2026\/03\/16\/saint-deniscahier-des-plaintes-doleances-et-remontrances-de-lassemblee-du-tiers-etat-de-la-ville-de-saint-denis\/","title":{"rendered":"SAINT-DENIS CAHIER Des plaintes, dol\u00e9ances, et remontrances de l\u2019assembl\u00e9e du tiers-\u00e9tat de la ville de Saint-Denis."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">SAINT-DENIS<br>CAHIER Des plaintes, dol\u00e9ances, et remontrances de l\u2019assembl\u00e9e du tiers-\u00e9tat de la ville de Saint-Denis.<br>Cette assembl\u00e9e a cru devoir se borner \u00e0 adh\u00e9rer aux demandes et remontrances desdites villes et bailliages en ce qui concerne les r\u00e9formations g\u00e9n\u00e9rales, et insister d\u2019une mani\u00e8re plus sp\u00e9ciale sur les abus locaux qui l\u2019int\u00e9ressent en particulier.<br>Article 1. La ville de Saint-Denis loge une partie des gens du Roi, huit fois par an habituellement, et douze fois lorsqu&rsquo;il y a des voyages de Compi\u00e8gne, sans compter les r\u00e9giments dans les mouvements de troupes et les remont\u00e9es habituelles. Le soin que l&rsquo;on a d&rsquo;\u00e9viter pour les troupes ordinaires le passage par Paris, rend leur s\u00e9jour \u00e0 Saint-Denis plus fr\u00e9quent que dans toutes les autres villes.<br>Cependant il existe \u00e0 Saint-Denis une caserne spacieuse, presque vacante, qui, pendant bien des ann\u00e9es, n&rsquo;a log\u00e9 qu&rsquo;une compagnie de grenadiers royaux, et qui loge actuellement une compagnie de recrues du r\u00e9giment du Roi.<br>Ind\u00e9pendamment des sommes consid\u00e9rables pour lesquelles la ville a contribu\u00e9 \u00e0 la construction de ce b\u00e2timent, les deniers de la commune ont \u00e9t\u00e9 plus qu&rsquo;\u00e9puis\u00e9s par la contrainte de fournir, pendant de longues ann\u00e9es, les meubles de la caserne, le bois pour le corps de garde et le linge pour les officiers, dont le blanchissage \u00e9tait encore rejet\u00e9 sur la ville, quoiqu&rsquo;il n&rsquo;exist\u00e2t aucune loi qui l&rsquo;assujett\u00eet \u00e0 toutes ces charges ; en sorte qu&rsquo;apr\u00e8s l&rsquo;\u00e9puisement des fonds communs, il a fallu en venir \u00e0 des impositions extraordinaires sur tous les habitants.<br>Depuis, l&rsquo;autorit\u00e9 a encore exig\u00e9 des fournitures de bois pour le corps de garde du d\u00e9p\u00f4t de mendicit\u00e9 ; ce n&rsquo;est qu&rsquo;\u00e0 force de r\u00e9sistance que la ville s&rsquo;est affranchie depuis peu de ces surcharges.<br>L&rsquo;assembl\u00e9e demande qu&rsquo;\u00e0 l&rsquo;exception du pavillon occup\u00e9 par la compagnie r\u00e9sidante aux casernes, le surplus soit employ\u00e9 \u00e0 loger les r\u00e9giments de passage, \u00e0 la d\u00e9charge des habitants.<br>Article 2. Il a \u00e9t\u00e9 \u00e9tabli un d\u00e9p\u00f4t de mendicit\u00e9 dans le plus beau quartier de la ville ; tr\u00e8s fr\u00e9quemment des mendiants s&rsquo;\u00e9chappent et passent dans les maisons voisines ; ces incidents y causent toujours des alarmes et donnent pr\u00e9texte aux soldats du corps de garde de s&rsquo;y introduire ; il en r\u00e9sulte une diminution r\u00e9elle de la valeur des maisons voisines et de leur location.<br>L&rsquo;assembl\u00e9e demande que ce d\u00e9p\u00f4t soit plac\u00e9 hors de la ville.<br>Article 3. L&rsquo;assembl\u00e9e demande, en outre, la suppression de plusieurs droits seigneuriaux, \u00e9nonc\u00e9s en un tarif du 27 f\u00e9vrier 1738, et perceptibles sur les charbons, bateaux, avoines, bl\u00e9s, l\u00e9gumes, etc. ;<br>Et celle de p\u00e9ages, barrages, botages et travers, tant par eau que par terre, attendu que ce droit est per\u00e7u jusqu&rsquo;\u00e0 trois fois sur les commer\u00e7ants domicili\u00e9s.<br>Article 4. La suppression des plombs sur les toiles peintes fabriqu\u00e9es en cette ville, comme g\u00eanant le commerce et nuisibles \u00e0 la perfection de l&rsquo;appr\u00eat des toiles, se r\u00e9f\u00e9rant \u00e0 ce qui a \u00e9t\u00e9 expos\u00e9 par le cahier du tiers-\u00e9tat de la ville de Rouen, article 71.<br>Article 5. Que les lettres pour cette ville ne soient tax\u00e9es \u00e0 la poste que conform\u00e9ment au tarif du 8 juillet 1759, dont les fermiers des postes s&rsquo;\u00e9cartent arbitrairement, depuis environ un an,<br>Et que tous privil\u00e8ges exclusifs pour les messageries soient supprim\u00e9s.<br>Arr\u00eat\u00e9 en l&rsquo;assembl\u00e9e tenue en l&rsquo;h\u00f4tel de ville de Saint-Denis en France, le 15 avril 1789.<br>Sign\u00e9 Hochereaux, maire ; Chatelle ; Carpentier ; Maillet ; Tresfenscheid ; P. Fournier ; Tinthoin ; Pouet ; Bleure ; Grenu ; Deblesson fils ; D\u00e9jobert ; Gillet ; Lorget ; Boucyr ; Porte ; Maillet ; Antoine ; Leb\u00e8gue ; Villiers ; Prud&rsquo;homme ; Carron ; Parain ; Legrand ; Berger ; Legobe ; R.-L. Cadot ; Vaudrelan ; Arnoult ; Guilbert ; Chartier ; Boulay ; Edi ; P. Guiard, et Linotte<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#1789 #93200<\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><\/h1>\n\n\n\n<h1 class=\"wp-block-heading\"><\/h1>\n\n\n\n<h1 class=\"wp-block-heading\"><\/h1>\n\n\n\n<h1 class=\"wp-block-heading\"><\/h1>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"1789 Saint Denis 93200 Cahier Doleances\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/XWjTucrBp8Y?start=35&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAINT-DENISCAHIER Des plaintes, dol\u00e9ances, et remontrances de l\u2019assembl\u00e9e du tiers-\u00e9tat de la ville de Saint-Denis.Cette assembl\u00e9e a cru devoir se borner \u00e0 adh\u00e9rer aux demandes et remontrances desdites villes et bailliages en ce qui concerne les r\u00e9formations g\u00e9n\u00e9rales, et insister &hellip; <a href=\"https:\/\/nakara.org\/index.php\/2026\/03\/16\/saint-deniscahier-des-plaintes-doleances-et-remontrances-de-lassemblee-du-tiers-etat-de-la-ville-de-saint-denis\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-44","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/comments?post=44"}],"version-history":[{"count":2,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts\/44\/revisions"}],"predecessor-version":[{"id":47,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/posts\/44\/revisions\/47"}],"wp:attachment":[{"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/media?parent=44"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/categories?post=44"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nakara.org\/index.php\/wp-json\/wp\/v2\/tags?post=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}